{"id":1338,"date":"2026-02-10T16:18:17","date_gmt":"2026-02-10T15:18:17","guid":{"rendered":"https:\/\/cyberforgood.org\/?p=1338"},"modified":"2026-02-10T16:18:19","modified_gmt":"2026-02-10T15:18:19","slug":"giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs","status":"publish","type":"post","link":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/","title":{"rendered":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb"},"content":{"rendered":"\n<p><strong>Quelle est la mission d&rsquo;Access Now ?<\/strong><\/p>\n\n\n\n<p><strong>Giulio Coppi I<\/strong> Access Now travaille sur deux volets principaux. D&rsquo;une part, nous avons la Digital Helpline, une assistance technique ouverte 24 heures sur 24, 7 jours sur 7, en 10 langues. Elle effectue des analyses forensic sur les logiciels malveillants (*malware, spyware) et les compromissions de compte. Cette assistance est d\u00e9di\u00e9e aux d\u00e9fenseurs des droits de l&rsquo;homme, aux activistes et aux journalistes dans les pays en conflit.<br><br>D&rsquo;autre part, le volet Advocacy \u2014 dont je fais partie \u2014 d\u00e9veloppe des campagnes, comme la coalition KeepItOn qui regroupe plus de 300 ONG r\u00e9pertoriant l\u2019ensemble des coupures Internet \u00e0 travers le monde. D\u00e8s qu&rsquo;une coupure est signal\u00e9e, nous faisons des v\u00e9rifications techniques par des sous-traitants entra\u00een\u00e9s pour d\u00e9terminer la source du probl\u00e8me (fournisseur de t\u00e9l\u00e9communication, cyber attaque, ou action gouvernementale) avant de lancer une campagne publique de d\u00e9nonciation et d&rsquo;appel au r\u00e9tablissement de l&rsquo;acc\u00e8s. Personnellement, j\u2019essaye aussi d\u2019\u00e9tablir une d\u00e9finition coordonn\u00e9e et reconnue du concept de \u00ab\u00a0shutdown\u00a0\u00bb au niveau international en utilisant les donn\u00e9es que nous apporte la campagne KeepItOn.<br><br><strong>En quoi les \u00ab\u00a0shutdowns\u00a0\u00bb repr\u00e9sentent une attaque envers la d\u00e9mocratie ?<\/strong><br><br><strong>Giulio Coppi I <\/strong>On s\u2019aper\u00e7oit de plus en plus que l\u2019interconnectivit\u00e9 des individus est attaqu\u00e9e par des r\u00e9gimes r\u00e9pressifs, notamment au travers de \u00ab\u00a0shutdowns\u00a0\u00bb. La raison de l\u2019augmentation de ces attaques est due au fait qu\u2019il existe une forte relation entre l&rsquo;acc\u00e8s \u00e0 l&rsquo;internet et les droits que les individus peuvent r\u00e9aliser. C\u2019est cette d\u00e9pendance entre l\u2019\u00eatre connect\u00e9 et la capacit\u00e9 \u00e0 interagir avec cet espace social qui devient un caract\u00e8re crucial de l\u2019interconnectivit\u00e9, et qui est mise en danger par les \u00ab\u00a0shutdowns.\u00a0\u00bb<br><br>Si cette dynamique de d\u00e9pendance est facilement reconnue par les acteurs de la d\u00e9mocratie, elle n\u2019est pas encore int\u00e9rioris\u00e9e. J\u2019ai entendu beaucoup d\u2019entre eux me dire \u201cOui, c\u2019est vrai, on reconna\u00eet qu\u2019il y a l\u00e0 un probl\u00e8me. \u201d. Mais aucun d\u2019eux n\u2019arrive \u00e0 lier cette probl\u00e9matique \u00e0 des actions. C\u2019est l\u00e0 que repose l\u2019int\u00e9r\u00eat d\u2019imposer un cadre l\u00e9gal aux concepts de \u00ab\u00a0shutdown.\u00a0\u00bb<br><br><strong>Pourquoi l\u2019\u00e9tablissement d\u2019une d\u00e9finition des \u00ab\u00a0shutdowns\u00a0\u00bb au niveau juridique est-il compliqu\u00e9 ?<br><\/strong><br><strong>Giulio Coppi I <\/strong>Je dirai m\u00eame que c\u2019est extr\u00eamement compliqu\u00e9. Du c\u00f4t\u00e9 des \u00ab\u00a0droits de l&rsquo;Homme\u00a0\u00bb, il est facile d&rsquo;\u00e9tablir des connexions solides entre la connectivit\u00e9 et les droits de communication, d&rsquo;information ou de rassemblement.<br><br>A l\u2019inverse,\u00a0 le \u00ab\u00a0droit international humanitaire\u00a0\u00bb est flou, puisqu\u2019il est uniquement pr\u00e9sent lorsque les autres droits s\u2019en vont. Il agit en quelque sorte comme un parapluie, lorsque plus rien ne reste. Il est principalement constitu\u00e9 de soft law qui d\u00e9crivent plut\u00f4t le positionnement des \u00c9tats par rapport \u00e0 la guerre, les r\u00e8gles qu\u2019ils s\u2019imposent dans cette situation, comme les lois de d\u00e9tention, des combattants\u2026 Dans le droit international humanitaire, il n\u2019est m\u00eame pas inscrit le droit \u00e0 la vie pour les combattants ! C\u2019est le jeu de la guerre. Certains vivent, d\u2019autres non. Et lorsque l\u2019on commence \u00e0 tirer, cette r\u00e9alit\u00e9 devient \u00e9vidente. C\u2019est donc facile de comprendre que le principe de \u00ab\u00a0shutdowns\u00a0\u00bb n\u2019est pas \u00e9crit dedans.<br><br>Et pourtant, si ce genre de droits est relay\u00e9 en second plan, on sait tous que les centres de communication ont toujours \u00e9t\u00e9 historiquement les premi\u00e8res cibles en temps de guerre. Et d&rsquo;une fa\u00e7on ou d\u2019une autre, on a d\u00fb transporter tout \u00e7a dans l&rsquo;\u00e2ge et l&rsquo;\u00e9poque de l&rsquo;Internet. Il s\u2019agit presque d\u2019une forme de tradition militaire, h\u00e9rit\u00e9e des tactiques des ann\u00e9es 60 et 70.<\/p>\n\n\n\n<p>On consid\u00e8re alors qu\u2019il est compl\u00e8tement normal de couper l\u2019Internet de million de personnes, simplement parce qu\u2019il s\u2019agit d\u2019un outil de communication.<br><br>Il y a quand m\u00eame des pistes qui pourraient permettre de donner un sens l\u00e9gal au \u00ab\u00a0shutdown.\u00a0\u00bb Dans le droit international humanitaire, il existe la notion de ciblage. Prenons l\u2019exemple de l\u2019Ukraine et des usines de fabrication de drones: il ne serait pas possible pour la Russie de raser compl\u00e8tement l\u2019une de ces usines. Les travailleurs participent-ils \u00e0 l\u2019effort de guerre ? Bien s\u00fbr. Mais pour autant il est impossible de lier directement la vie des assembleurs de drones et les morts sur les champs de bataille. Il faut avertir les travailleurs pour s\u2019assurer de ne pas les tuer lorsque l\u2019usine sera ras\u00e9e. Dans l\u2019\u00e2ge d\u2019Internet toutes ces notions deviennent des amalgames, et personne n\u2019est vraiment capable de les d\u00e9m\u00ealer.<br><br>Mon travail c&rsquo;est justement d&rsquo;essayer de construire un cadre logique qui me permet d&rsquo;aller vers les Nations-Unies ou la France, et de dire : \u201cVous devez consid\u00e9rer dans vos positions nationales que le ciblage de l&rsquo;infrastructure num\u00e9rique doit se faire selon le droit de la guerre\u201d.<br><br><strong>Dans des cas de mouvements populaires comme au N\u00e9pal, comment le \u00ab\u00a0shutdown\u00a0\u00bb est-il per\u00e7u par les individus ?<\/strong><br><br><strong>Giulio Coppi I<\/strong> Dans des cas comme le N\u00e9pal ou la Nouvelle-Cal\u00e9donie, le shutdown montre \u00e0 quel point cette action ne sert strictement \u00e0 rien pour stopper les mouvements de r\u00e9volte. Au contraire, cela augmente les tensions.<br><br>Les gens se rendent compte que couper la connectivit\u00e9 est une vraie attaque politique. Ce n&rsquo;est pas un simple d\u00e9rangement technique, mais un acte d\u00e9lib\u00e9r\u00e9 visant \u00e0 couper l&rsquo;acc\u00e8s \u00e0 l&rsquo;information et \u00e0 la coordination, per\u00e7u comme un levier de pouvoir de l&rsquo;\u00c9tat. Dans le cas du N\u00e9pal, le shutdown a m\u00eame \u00e9t\u00e9 l&rsquo;un des \u00e9l\u00e9ments d\u00e9clencheurs de la r\u00e9volte.<br><br><strong>Selon vous la France est-elle suffisamment \u00e9quip\u00e9e contre les risques de shutdown ?<\/strong><br><strong><br>Giulio Coppi I<\/strong> Contrairement aux acteurs d\u2019Am\u00e9rique latine, du Moyen-Orient (pays arabophones comme le Liban, la Palestine) et de l\u2019Asie du Sud-Est (Myanmar, Tha\u00eflande), qui sont tr\u00e8s coordonn\u00e9s, et forment des r\u00e9seaux, la France est un maillon faible dans cet \u00e9cosyst\u00e8me.<br><br>En France, n\u2019\u00e9tant jamais expos\u00e9s \u00e0 ce genre de menaces, le r\u00e9seau n\u2019a jamais eu le temps de se former. <br><br>Selon moi, la France est trop concentr\u00e9e sur Bruxelles et ses actions politiques, comme la confidentialit\u00e9 et la protection des donn\u00e9es, et ignore la g\u00e9opolitique et l&rsquo;impact global. Les anciennes colonies comme le Niger, le Mali ou la R\u00e9publique centrafricaine, qui sont bien plus expos\u00e9es que la France se retrouvent donc en dehors de tout r\u00e9seau, et ce \u00e0 cause de la continuation de politique n\u00e9ocoloniales dans le domaine du num\u00e9rique et de la tech, qui les exposent \u00e0 devenir le terrain de bataille entre pouvoir \u00e9trangers. D\u2019une part, l&rsquo;absence de mise en relation avec le r\u00e9seau francophone \u2013 due \u00e0 leur obsession pour Bruxelles \u2013 marginalise ces pays. D\u2019autres parts, les acteurs globaux op\u00e9rant sur des r\u00e9seaux anglophones sont dans l\u2019incapacit\u00e9 de r\u00e9pondre \u00e0 leurs besoins. Les artefacts de la colonisation les emp\u00eachent donc d\u2019acc\u00e9der aux ressources de financement accessibles \u00e0 d\u2019autres acteurs dans la r\u00e9gion, renfor\u00e7ant encore plus cet effet de marginalisation.<br><br>L&rsquo;absence de mise en relation du r\u00e9seau francophone est juste un facteur de plus qui fait que les acteurs locaux sont d&rsquo;un c\u00f4t\u00e9 ignor\u00e9s par les acteurs europ\u00e9ens obs\u00e9d\u00e9s par Bruxelles, et sont exclus par les autres acteurs globaux qui op\u00e8rent surtout sur des plateformes et r\u00e9seaux anglophones. Cela se traduit en marginalisation et exclusion des sources de funding qui sont accessibles \u00e0 la soci\u00e9t\u00e9 civile dans des autres pays de la r\u00e9gion ou la Big Tech est plus pr\u00e9sente et les bailleurs financent des projets li\u00e9s au \u00ab\u00a0digital rights\u00a0\u00bb.<br><br>La seule d\u00e9fense r\u00e9elle contre les attaques en ligne, y compris les shutdowns, est une \u00ab\u00a0soci\u00e9t\u00e9 civile forte\u00a0\u00bb qui peut s&rsquo;\u00e9lever contre les abus. Et si l&rsquo;on ne soutient pas cet \u00e9cosyst\u00e8me, on se retrouve seul en cas d&rsquo;attaque, quel que soit la quantit\u00e9 de campagnes d\u2019information ou d\u2019\u00e9ducation que l\u2019on a pu faire. R\u00e9armer la soci\u00e9t\u00e9 civile avec des outils de protection de l\u2019information passe aussi par un changement de mentalit\u00e9 et de point de vue de la France. Comment peut-on brandir le \u201cTech for Good\u201d sans s\u2019engager s\u00e9rieusement sur les droits des individus par rapport \u00e0 la technologie ? \u00c0 cause de ce manque d\u2019actions et de r\u00e9flexions, la soci\u00e9t\u00e9 civile fran\u00e7aise est aust\u00e8re et affaiblie.<br><br><strong>Comment peut-on concilier acc\u00e8s \u00e0 l\u2019information et principe de neutralit\u00e9 ?<br><\/strong><br><strong>Giulio Coppi I<\/strong> Chez Access Now nous faisons une distinction tr\u00e8s importante entre \u00ab\u00a0principe de neutralit\u00e9 du moyen et du contenu.\u00a0\u00bb Les moyens d\u2019acc\u00e8s \u00e0 l\u2019information doivent \u00eatre compl\u00e8tement neutre. Et c\u2019est aux \u00c9tats et aux entreprises de la Big Tech de se coordonner pour s\u2019assurer d\u2019une neutralit\u00e9 de tous les moyens de communication. Pour le contenu, chaque individu doit \u00eatre libre de poster et regarder les informations qu\u2019il veut, tout en restant dans un cadre bien d\u00e9limit\u00e9 par la loi.<br><br>L\u00e0 o\u00f9 Access Now peut agir, c\u2019est en s\u2019assurant que les moyens de communication que l\u2019on donne aux acteurs de la d\u00e9mocratie soient neutres. Pour cela, des VPN ou connexions satellites permettent d\u2019acc\u00e9der aux informations globales. Il faut cependant bien s\u2019assurer d\u00e8s lors que ces technologies ne mettent pas en danger la vie de leur utilisateur, et donc adapter les solutions propos\u00e9es en fonction des situations.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelle est la mission d&rsquo;Access Now ? Giulio Coppi I Access Now travaille sur deux volets principaux. D&rsquo;une part, nous avons la Digital Helpline, une assistance technique ouverte 24 heures&#8230;<\/p>\n","protected":false},"author":3,"featured_media":807,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,12],"tags":[14],"class_list":["post-1338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyber-en","category-cyber","tag-interview"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good\" \/>\n<meta property=\"og:description\" content=\"Quelle est la mission d&rsquo;Access Now ? Giulio Coppi I Access Now travaille sur deux volets principaux. D&rsquo;une part, nous avons la Digital Helpline, une assistance technique ouverte 24 heures...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/\" \/>\n<meta property=\"og:site_name\" content=\"Cyber for Good\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-10T15:18:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T15:18:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png\" \/>\n\t<meta property=\"og:image:width\" content=\"342\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"ninon.bonnet-de-paillerets@afpp.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"ninon.bonnet-de-paillerets@afpp.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/\"},\"author\":{\"name\":\"ninon.bonnet-de-paillerets@afpp.fr\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#\\\/schema\\\/person\\\/a56cc579b04306585c45b07d2c601721\"},\"headline\":\"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb\",\"datePublished\":\"2026-02-10T15:18:17+00:00\",\"dateModified\":\"2026-02-10T15:18:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/\"},\"wordCount\":1670,\"publisher\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sebestien-Courou.png\",\"keywords\":[\"Interview\"],\"articleSection\":[\"Cyber\",\"Cyber\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/\",\"url\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/\",\"name\":\"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sebestien-Courou.png\",\"datePublished\":\"2026-02-10T15:18:17+00:00\",\"dateModified\":\"2026-02-10T15:18:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sebestien-Courou.png\",\"contentUrl\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Sebestien-Courou.png\",\"width\":342,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/\",\"name\":\"Cyber for Good\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#organization\",\"name\":\"Cyber for Good\",\"url\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CFG.svg\",\"contentUrl\":\"https:\\\/\\\/cyberforgood.org\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Logo-CFG.svg\",\"caption\":\"Cyber for Good\"},\"image\":{\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/#\\\/schema\\\/person\\\/a56cc579b04306585c45b07d2c601721\",\"name\":\"ninon.bonnet-de-paillerets@afpp.fr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g\",\"caption\":\"ninon.bonnet-de-paillerets@afpp.fr\"},\"url\":\"https:\\\/\\\/cyberforgood.org\\\/fr\\\/author\\\/ninon-bonnet-de-pailleretsafpp-fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/","og_locale":"fr_FR","og_type":"article","og_title":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good","og_description":"Quelle est la mission d&rsquo;Access Now ? Giulio Coppi I Access Now travaille sur deux volets principaux. D&rsquo;une part, nous avons la Digital Helpline, une assistance technique ouverte 24 heures...","og_url":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/","og_site_name":"Cyber for Good","article_published_time":"2026-02-10T15:18:17+00:00","article_modified_time":"2026-02-10T15:18:19+00:00","og_image":[{"width":342,"height":400,"url":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png","type":"image\/png"}],"author":"ninon.bonnet-de-paillerets@afpp.fr","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"ninon.bonnet-de-paillerets@afpp.fr","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#article","isPartOf":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/"},"author":{"name":"ninon.bonnet-de-paillerets@afpp.fr","@id":"https:\/\/cyberforgood.org\/fr\/#\/schema\/person\/a56cc579b04306585c45b07d2c601721"},"headline":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb","datePublished":"2026-02-10T15:18:17+00:00","dateModified":"2026-02-10T15:18:19+00:00","mainEntityOfPage":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/"},"wordCount":1670,"publisher":{"@id":"https:\/\/cyberforgood.org\/fr\/#organization"},"image":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#primaryimage"},"thumbnailUrl":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png","keywords":["Interview"],"articleSection":["Cyber","Cyber"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/","url":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/","name":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb - Cyber for Good","isPartOf":{"@id":"https:\/\/cyberforgood.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#primaryimage"},"image":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#primaryimage"},"thumbnailUrl":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png","datePublished":"2026-02-10T15:18:17+00:00","dateModified":"2026-02-10T15:18:19+00:00","breadcrumb":{"@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#primaryimage","url":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png","contentUrl":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/10\/Sebestien-Courou.png","width":342,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/cyberforgood.org\/fr\/giulio-coppi-couper-internet-devient-larme-des-pouvoirs-repressifs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/cyberforgood.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Giulio Coppi : \u00ab Couper Internet devient l\u2019arme des pouvoirs r\u00e9pressifs \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/cyberforgood.org\/fr\/#website","url":"https:\/\/cyberforgood.org\/fr\/","name":"Cyber for Good","description":"","publisher":{"@id":"https:\/\/cyberforgood.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cyberforgood.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cyberforgood.org\/fr\/#organization","name":"Cyber for Good","url":"https:\/\/cyberforgood.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cyberforgood.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/09\/Logo-CFG.svg","contentUrl":"https:\/\/cyberforgood.org\/wp-content\/uploads\/2025\/09\/Logo-CFG.svg","caption":"Cyber for Good"},"image":{"@id":"https:\/\/cyberforgood.org\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/cyberforgood.org\/fr\/#\/schema\/person\/a56cc579b04306585c45b07d2c601721","name":"ninon.bonnet-de-paillerets@afpp.fr","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/233a668b06ef83073574f1392373a661c94a7dec69d68e924741ad2cd074d6ff?s=96&d=mm&r=g","caption":"ninon.bonnet-de-paillerets@afpp.fr"},"url":"https:\/\/cyberforgood.org\/fr\/author\/ninon-bonnet-de-pailleretsafpp-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/posts\/1338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/comments?post=1338"}],"version-history":[{"count":5,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/posts\/1338\/revisions"}],"predecessor-version":[{"id":1343,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/posts\/1338\/revisions\/1343"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/media\/807"}],"wp:attachment":[{"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/media?parent=1338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/categories?post=1338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cyberforgood.org\/fr\/wp-json\/wp\/v2\/tags?post=1338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}